{"id":171216,"date":"2025-03-19T11:00:22","date_gmt":"2025-03-19T06:00:22","guid":{"rendered":"https:\/\/kmsnews.org\/kms\/?p=171216"},"modified":"2025-03-19T15:33:47","modified_gmt":"2025-03-19T10:33:47","slug":"raws-covert-actions-pose-biggest-threat-to-south-asia","status":"publish","type":"post","link":"https:\/\/kmsnews.org\/kms\/2025\/03\/19\/raws-covert-actions-pose-biggest-threat-to-south-asia.html","title":{"rendered":"RAW\u2019s covert actions pose biggest threat to South Asia"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-171217\" src=\"https:\/\/kmsnews.org\/kms\/assests\/2025\/03\/RAW-blog.jpg\" alt=\"\" width=\"890\" height=\"395\" \/>New Delhi: Obsessed with dominance across South Asia, India is using its intelligence agency, RAW, to orchestrate unrest in neighboring countries.<\/p>\n<p>According to Kashmir Media Service, India and its RAW have left behind a bloody legacy\u2014fueling civil war in Sri Lanka, political turmoil in Bangladesh, and sustaining a military dictatorship in Myanmar.<\/p>\n<p>India has been training the LTTE in Sri Lanka, supporting insurgencies in Myanmar and manipulating Bangladesh\u2019s politics through RAW\u2019s covert operations.<\/p>\n<p>In Sri Lanka, RAW\u2019s involvement extended beyond the LTTE, where India is responsible for decades of bloodshed, including alleged links to the 2019 Easter Sunday bombings to install a pro-India regime.<\/p>\n<p>In Bangladesh, India\u2019s Border Security Force continues to operate with impunity, turning the border into an execution zone. The ouster of Sheikh Hasina from government was a backlash over India\u2019s interference.<\/p>\n<p>Meanwhile, India\u2019s double game in Myanmar is evident. Despite signing international arms control agreements, it continues to supply weapons to the military junta, which is perpetrating war crimes against civilians.<\/p>\n<p>RAW\u2019s operations prove that South Asia\u2019s biggest threat is not external terrorism but India\u2019s relentless interference, which fuels wars, props up dictators and destabilizes entire nations for its Hindutva ideology .<\/p>\n","protected":false},"excerpt":{"rendered":"<p>New Delhi: Obsessed with dominance across South Asia, India is using its intelligence agency, RAW, to orchestrate unrest in neighboring countries. According to Kashmir Media Service, India and its RAW have left behind a bloody legacy\u2014fueling civil war in Sri Lanka, political turmoil in Bangladesh, and sustaining a military dictatorship in Myanmar. India has been &hellip;<\/p>\n","protected":false},"author":1,"featured_media":171217,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[14],"tags":[5],"class_list":["post-171216","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-india","tag-top-story"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>RAW\u2019s covert actions pose biggest threat to South Asia &#062; Kashmir Media Service<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kmsnews.org\/kms\/2025\/03\/19\/raws-covert-actions-pose-biggest-threat-to-south-asia.html\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"RAW\u2019s covert actions pose biggest threat to South Asia &#062; Kashmir Media Service\" \/>\n<meta property=\"og:description\" content=\"New Delhi: Obsessed with dominance across South Asia, India is using its intelligence agency, RAW, to orchestrate unrest in neighboring countries. According to Kashmir Media Service, India and its RAW have left behind a bloody legacy\u2014fueling civil war in Sri Lanka, political turmoil in Bangladesh, and sustaining a military dictatorship in Myanmar. India has been &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kmsnews.org\/kms\/2025\/03\/19\/raws-covert-actions-pose-biggest-threat-to-south-asia.html\" \/>\n<meta property=\"og:site_name\" content=\"Kashmir Media Service\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-19T06:00:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-19T10:33:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kmsnews.org\/kms\/assests\/2025\/03\/RAW-blog.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"890\" \/>\n\t<meta property=\"og:image:height\" content=\"395\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"webadmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"webadmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/kmsnews.org\\\/kms\\\/2025\\\/03\\\/19\\\/raws-covert-actions-pose-biggest-threat-to-south-asia.html#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kmsnews.org\\\/kms\\\/2025\\\/03\\\/19\\\/raws-covert-actions-pose-biggest-threat-to-south-asia.html\"},\"author\":{\"name\":\"webadmin\",\"@id\":\"https:\\\/\\\/kmsnews.org\\\/kms\\\/#\\\/schema\\\/person\\\/883975b5acf9316fe91b838bbcb447ab\"},\"headline\":\"RAW\u2019s covert actions pose biggest threat to South Asia\",\"datePublished\":\"2025-03-19T06:00:22+00:00\",\"dateModified\":\"2025-03-19T10:33:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/kmsnews.org\\\/kms\\\/2025\\\/03\\\/19\\\/raws-covert-actions-pose-biggest-threat-to-south-asia.html\"},\"wordCount\":214,\"image\":{\"@id\":\"https:\\\/\\\/kmsnews.org\\\/kms\\\/2025\\\/03\\\/19\\\/raws-covert-actions-pose-biggest-threat-to-south-asia.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kmsnews.org\\\/kms\\\/assests\\\/2025\\\/03\\\/RAW-blog.jpg\",\"keywords\":[\"Top Story\"],\"articleSection\":[\"India\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kmsnews.org\\\/kms\\\/2025\\\/03\\\/19\\\/raws-covert-actions-pose-biggest-threat-to-south-asia.html\",\"url\":\"https:\\\/\\\/kmsnews.org\\\/kms\\\/2025\\\/03\\\/19\\\/raws-covert-actions-pose-biggest-threat-to-south-asia.html\",\"name\":\"RAW\u2019s covert actions pose biggest threat to South Asia &#062; Kashmir Media Service\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kmsnews.org\\\/kms\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kmsnews.org\\\/kms\\\/2025\\\/03\\\/19\\\/raws-covert-actions-pose-biggest-threat-to-south-asia.html#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kmsnews.org\\\/kms\\\/2025\\\/03\\\/19\\\/raws-covert-actions-pose-biggest-threat-to-south-asia.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kmsnews.org\\\/kms\\\/assests\\\/2025\\\/03\\\/RAW-blog.jpg\",\"datePublished\":\"2025-03-19T06:00:22+00:00\",\"dateModified\":\"2025-03-19T10:33:47+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/kmsnews.org\\\/kms\\\/#\\\/schema\\\/person\\\/883975b5acf9316fe91b838bbcb447ab\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kmsnews.org\\\/kms\\\/2025\\\/03\\\/19\\\/raws-covert-actions-pose-biggest-threat-to-south-asia.html#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kmsnews.org\\\/kms\\\/2025\\\/03\\\/19\\\/raws-covert-actions-pose-biggest-threat-to-south-asia.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/kmsnews.org\\\/kms\\\/2025\\\/03\\\/19\\\/raws-covert-actions-pose-biggest-threat-to-south-asia.html#primaryimage\",\"url\":\"https:\\\/\\\/kmsnews.org\\\/kms\\\/assests\\\/2025\\\/03\\\/RAW-blog.jpg\",\"contentUrl\":\"https:\\\/\\\/kmsnews.org\\\/kms\\\/assests\\\/2025\\\/03\\\/RAW-blog.jpg\",\"width\":890,\"height\":395},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kmsnews.org\\\/kms\\\/2025\\\/03\\\/19\\\/raws-covert-actions-pose-biggest-threat-to-south-asia.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kmsnews.org\\\/kms\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"RAW\u2019s covert actions pose biggest threat to South Asia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kmsnews.org\\\/kms\\\/#website\",\"url\":\"https:\\\/\\\/kmsnews.org\\\/kms\\\/\",\"name\":\"Kashmir Media Service\",\"description\":\"Latest and Breaking News from Kashmir and India\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kmsnews.org\\\/kms\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/kmsnews.org\\\/kms\\\/#\\\/schema\\\/person\\\/883975b5acf9316fe91b838bbcb447ab\",\"name\":\"webadmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ec810018841518562f8af46d9e5fc866103bb5f2171f7d136d33db5f28ae5691?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ec810018841518562f8af46d9e5fc866103bb5f2171f7d136d33db5f28ae5691?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ec810018841518562f8af46d9e5fc866103bb5f2171f7d136d33db5f28ae5691?s=96&d=mm&r=g\",\"caption\":\"webadmin\"},\"sameAs\":[\"https:\\\/\\\/kmsnews.org\\\/en\"],\"url\":\"https:\\\/\\\/kmsnews.org\\\/kms\\\/author\\\/webadmin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"RAW\u2019s covert actions pose biggest threat to South Asia &#062; Kashmir Media Service","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kmsnews.org\/kms\/2025\/03\/19\/raws-covert-actions-pose-biggest-threat-to-south-asia.html","og_locale":"en_US","og_type":"article","og_title":"RAW\u2019s covert actions pose biggest threat to South Asia &#062; Kashmir Media Service","og_description":"New Delhi: Obsessed with dominance across South Asia, India is using its intelligence agency, RAW, to orchestrate unrest in neighboring countries. According to Kashmir Media Service, India and its RAW have left behind a bloody legacy\u2014fueling civil war in Sri Lanka, political turmoil in Bangladesh, and sustaining a military dictatorship in Myanmar. India has been &hellip;","og_url":"https:\/\/kmsnews.org\/kms\/2025\/03\/19\/raws-covert-actions-pose-biggest-threat-to-south-asia.html","og_site_name":"Kashmir Media Service","article_published_time":"2025-03-19T06:00:22+00:00","article_modified_time":"2025-03-19T10:33:47+00:00","og_image":[{"width":890,"height":395,"url":"https:\/\/kmsnews.org\/kms\/assests\/2025\/03\/RAW-blog.jpg","type":"image\/jpeg"}],"author":"webadmin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"webadmin","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/kmsnews.org\/kms\/2025\/03\/19\/raws-covert-actions-pose-biggest-threat-to-south-asia.html#article","isPartOf":{"@id":"https:\/\/kmsnews.org\/kms\/2025\/03\/19\/raws-covert-actions-pose-biggest-threat-to-south-asia.html"},"author":{"name":"webadmin","@id":"https:\/\/kmsnews.org\/kms\/#\/schema\/person\/883975b5acf9316fe91b838bbcb447ab"},"headline":"RAW\u2019s covert actions pose biggest threat to South Asia","datePublished":"2025-03-19T06:00:22+00:00","dateModified":"2025-03-19T10:33:47+00:00","mainEntityOfPage":{"@id":"https:\/\/kmsnews.org\/kms\/2025\/03\/19\/raws-covert-actions-pose-biggest-threat-to-south-asia.html"},"wordCount":214,"image":{"@id":"https:\/\/kmsnews.org\/kms\/2025\/03\/19\/raws-covert-actions-pose-biggest-threat-to-south-asia.html#primaryimage"},"thumbnailUrl":"https:\/\/kmsnews.org\/kms\/assests\/2025\/03\/RAW-blog.jpg","keywords":["Top Story"],"articleSection":["India"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/kmsnews.org\/kms\/2025\/03\/19\/raws-covert-actions-pose-biggest-threat-to-south-asia.html","url":"https:\/\/kmsnews.org\/kms\/2025\/03\/19\/raws-covert-actions-pose-biggest-threat-to-south-asia.html","name":"RAW\u2019s covert actions pose biggest threat to South Asia &#062; Kashmir Media Service","isPartOf":{"@id":"https:\/\/kmsnews.org\/kms\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kmsnews.org\/kms\/2025\/03\/19\/raws-covert-actions-pose-biggest-threat-to-south-asia.html#primaryimage"},"image":{"@id":"https:\/\/kmsnews.org\/kms\/2025\/03\/19\/raws-covert-actions-pose-biggest-threat-to-south-asia.html#primaryimage"},"thumbnailUrl":"https:\/\/kmsnews.org\/kms\/assests\/2025\/03\/RAW-blog.jpg","datePublished":"2025-03-19T06:00:22+00:00","dateModified":"2025-03-19T10:33:47+00:00","author":{"@id":"https:\/\/kmsnews.org\/kms\/#\/schema\/person\/883975b5acf9316fe91b838bbcb447ab"},"breadcrumb":{"@id":"https:\/\/kmsnews.org\/kms\/2025\/03\/19\/raws-covert-actions-pose-biggest-threat-to-south-asia.html#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kmsnews.org\/kms\/2025\/03\/19\/raws-covert-actions-pose-biggest-threat-to-south-asia.html"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/kmsnews.org\/kms\/2025\/03\/19\/raws-covert-actions-pose-biggest-threat-to-south-asia.html#primaryimage","url":"https:\/\/kmsnews.org\/kms\/assests\/2025\/03\/RAW-blog.jpg","contentUrl":"https:\/\/kmsnews.org\/kms\/assests\/2025\/03\/RAW-blog.jpg","width":890,"height":395},{"@type":"BreadcrumbList","@id":"https:\/\/kmsnews.org\/kms\/2025\/03\/19\/raws-covert-actions-pose-biggest-threat-to-south-asia.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kmsnews.org\/kms\/"},{"@type":"ListItem","position":2,"name":"RAW\u2019s covert actions pose biggest threat to South Asia"}]},{"@type":"WebSite","@id":"https:\/\/kmsnews.org\/kms\/#website","url":"https:\/\/kmsnews.org\/kms\/","name":"Kashmir Media Service","description":"Latest and Breaking News from Kashmir and India","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kmsnews.org\/kms\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/kmsnews.org\/kms\/#\/schema\/person\/883975b5acf9316fe91b838bbcb447ab","name":"webadmin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/ec810018841518562f8af46d9e5fc866103bb5f2171f7d136d33db5f28ae5691?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ec810018841518562f8af46d9e5fc866103bb5f2171f7d136d33db5f28ae5691?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ec810018841518562f8af46d9e5fc866103bb5f2171f7d136d33db5f28ae5691?s=96&d=mm&r=g","caption":"webadmin"},"sameAs":["https:\/\/kmsnews.org\/en"],"url":"https:\/\/kmsnews.org\/kms\/author\/webadmin"}]}},"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/kmsnews.org\/kms\/assests\/2025\/03\/RAW-blog.jpg","_links":{"self":[{"href":"https:\/\/kmsnews.org\/kms\/wp-json\/wp\/v2\/posts\/171216","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kmsnews.org\/kms\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kmsnews.org\/kms\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kmsnews.org\/kms\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/kmsnews.org\/kms\/wp-json\/wp\/v2\/comments?post=171216"}],"version-history":[{"count":2,"href":"https:\/\/kmsnews.org\/kms\/wp-json\/wp\/v2\/posts\/171216\/revisions"}],"predecessor-version":[{"id":171220,"href":"https:\/\/kmsnews.org\/kms\/wp-json\/wp\/v2\/posts\/171216\/revisions\/171220"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kmsnews.org\/kms\/wp-json\/wp\/v2\/media\/171217"}],"wp:attachment":[{"href":"https:\/\/kmsnews.org\/kms\/wp-json\/wp\/v2\/media?parent=171216"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kmsnews.org\/kms\/wp-json\/wp\/v2\/categories?post=171216"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kmsnews.org\/kms\/wp-json\/wp\/v2\/tags?post=171216"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}