{"id":71955,"date":"2025-05-03T19:55:34","date_gmt":"2025-05-03T14:55:34","guid":{"rendered":"https:\/\/kmsnews.org\/urdu\/?p=71955"},"modified":"2025-05-03T19:55:34","modified_gmt":"2025-05-03T14:55:34","slug":"%d8%a8%da%be%d8%a7%d8%b1%d8%aa-%d8%af%da%be%d9%88%da%a9%db%81-%d8%af%db%81%db%8c-%da%a9%db%8c-%d8%a7%db%8c%da%a9-%da%af%da%be%d9%86%d8%a7%ef%ba%85%d9%86%db%8c-%d8%aa%d8%a7%d8%b1%db%8c%d8%ae-%d8%b1","status":"publish","type":"post","link":"https:\/\/kmsnews.org\/urdu\/71955","title":{"rendered":"\u0628\u06be\u0627\u0631\u062a \u062f\u06be\u0648\u06a9\u06c1 \u062f\u06c1\u06cc \u06a9\u06cc \u0627\u06cc\u06a9 \u06af\u06be\u0646\u0627\ufe85\u0646\u06cc \u062a\u0627\u0631\u06cc\u062e \u0631\u06a9\u06be\u062a\u0627 \u06c1\u06d2\u060c \u062d\u0631\u06cc\u062a \u06a9\u0627\u0646\u0641\u0631\u0646\u0633"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-71956\" src=\"https:\/\/kmsnews.org\/urdu\/assets\/2025\/05\/APHC.jpg\" alt=\"\" width=\"598\" height=\"400\" \/>\u0633\u0631\u06cc\u0646\u06af\u0631: \u0628\u06be\u0627\u0631\u062a \u06a9\u06d2 \u063a\u06cc\u0631 \u0642\u0627\u0646\u0648\u0646\u06cc \u0632\u06cc\u0631 \u0642\u0628\u0636\u06c1 \u062c\u0645\u0648\u06ba \u0648\u06a9\u0634\u0645\u06cc\u0631 \u0645\u06cc\u06ba \u06a9\u0644 \u062c\u0645\u0627\u0639\u062a\u06cc \u062d\u0631\u06cc\u062a \u06a9\u0627\u0646\u0641\u0631\u0646\u0633 \u0646\u06d2 \u06a9\u06c1\u0627 \u06c1\u06d2 \u06a9\u06c1 \u0628\u06be\u0627\u0631\u062a \u062f\u06be\u0648\u06a9\u06c1 \u062f\u06c1\u06cc \u0627\u0648\u0631 \u0648\u0639\u062f\u06c1 \u062e\u0644\u0627\u0641\u06cc \u06a9\u06cc \u0627\u06cc\u06a9 \u06af\u06be\u0646\u0627\ufe85\u0646\u06cc \u062a\u0627\u0631\u06cc\u062e \u0631\u06a9\u06be\u062a\u0627 \u06c1\u06d2 \u060c \u062c\u0645\u0648\u06ba \u0648\u06a9\u0634\u0645\u06cc\u0631 \u067e\u0631 \u0646\u0627\u062c\u0627\u0626\u0632 \u0628\u06be\u0627\u0631\u062a\u06cc \u062a\u0633\u0644\u0637 \u06a9\u06cc \u0648\u062c\u06c1 \u0633\u06d2 \u06cc\u06c1 \u067e\u0648\u0631\u0627 \u062e\u0637\u06c1 \u0645\u0633\u0644\u0633\u0644 \u0627\u06cc\u06a9 \u063a\u06cc\u0631 \u06cc\u0642\u06cc\u0646\u06cc \u0635\u0648\u0631\u062a\u062d\u0627\u0644 \u0633\u06d2 \u062f\u0648\u0686\u0627\u0631 \u06c1\u06d2\u06d4<br \/>\n\u06a9\u0634\u0645\u06cc\u0631 \u0645\u06cc\u0688\u06cc\u0627\u0633\u0631\u0648\u0633 \u06a9\u06d2 \u0645\u0637\u0627\u0628\u0642 \u062d\u0631\u06cc\u062a \u06a9\u0627\u0646\u0641\u0631\u0646\u0633 \u06a9\u06d2 \u062a\u0631\u062c\u0645\u0627\u0646 \u0627\u06cc\u0688\u0648\u0648\u06a9\u06cc\u0679 \u0639\u0628\u062f\u0627\u0644\u0631\u0634\u06cc\u062f \u0645\u0646\u06c1\u0627\u0633 \u0646\u06d2 \u0633\u0631\u06cc\u0646\u06af\u0631 \u0645\u06cc\u06ba \u062c\u0627\u0631\u06cc \u0627\u06cc\u06a9 \u0628\u06cc\u0627\u0646 \u0645\u06cc\u06ba \u06a9\u06c1\u0627 \u06a9\u06c1 \u0628\u06be\u0627\u0631\u062a \u0646\u06d2 \u0627\u0642\u0648\u0627\u0645 \u0645\u062a\u062d\u062f\u06c1 \u0627\u0648\u0631 \u067e\u0648\u0631\u06cc \u0639\u0627\u0644\u0645\u06cc \u0628\u0631\u0627\u062f\u06cc \u06a9\u06d2 \u0633\u0627\u0645\u0646\u06d2 \u06a9\u0634\u0645\u06cc\u0631\u06cc\u0648\u06ba \u06a9\u0648 \u0627\u0646\u06a9\u0627 \u067e\u06cc\u062f\u0627\u0626\u0634\u06cc \u062d\u0642 \u060c \u062d\u0642 \u062e\u0648\u062f \u0627\u0631\u0627\u062f\u06cc\u062a \u062f\u06cc\u0646\u06d2 \u06a9\u0627 \u0648\u0639\u062f\u06c1 \u06a9\u06cc\u0627 \u062a\u06be\u0627 \u0644\u06cc\u06a9\u0646 \u0648\u06c1 \u06cc\u06c1 \u0648\u0639\u062f\u06c1 \u067e\u0648\u0631\u0627 \u06a9\u0631\u0646\u06d2 \u06a9\u06d2 \u0628\u062c\u0627\u0626\u06d2 \u06a9\u0634\u0645\u06cc\u0631\u06cc\u0648\u06ba \u06a9\u0648 \u0622\u0632\u0627\u062f\u06cc \u06a9\u06d2 \u0645\u0637\u0627\u0644\u0628\u06d2 \u06a9\u06cc \u067e\u0627\u062f\u0627\u0634 \u0645\u06cc\u06ba \u06af\u0632\u0634\u062a\u06c1 77\u0628\u0631\u0633 \u0633\u06d2 \u062a\u062e\u062a\u06c1 \u0645\u0634\u0642 \u0628\u0646\u0627 \u0631\u06c1\u0627 \u06c1\u06d2\u06d4 \u0627\u0646\u06c1\u0648\u06ba\u0646\u06d2 \u06a9\u06c1\u0627 \u06a9\u06c1 \u067e\u06c1\u0644\u06af\u0627\u0645 \u06a9\u0627 \u0648\u0627\u0642\u0639\u06c1 \u0628\u06be\u06cc \u067e\u0644\u0648\u0627\u0645\u06c1 \u062d\u0645\u0644\u06d2 \u06a9\u06cc \u0637\u0631\u062d \u0627\u06cc\u06a9 \u0627\u0648\u0631 \u0628\u06be\u0627\u0631\u062a\u06cc \u0688\u0631\u0627\u0645\u06c1 \u06c1\u06d2 \u062c\u0633\u06a9\u0627 \u0648\u0627\u062d\u062f \u0645\u0642\u0635\u062f \u06a9\u0634\u0645\u06cc\u0631\u06cc\u0648\u06ba \u06a9\u06cc \u067e\u0631\u0627\u0645\u0646 \u062c\u062f\u0648\u062c\u06c1\u062f \u0622\u0632\u0627\u062f\u06cc \u06a9\u0648 \u0628\u062f\u0646\u0627\u0645 \u06a9\u0631\u0646\u0627 \u0627\u0648\u0631 \u067e\u0627\u06a9\u0633\u062a\u0627\u0646 \u06a9\u06d2 \u0633\u0631 \u062f\u06c1\u0634\u062a \u06af\u0631\u062f\u06cc \u06a9\u0627 \u0627\u0644\u0632\u0627\u0645 \u062a\u06be\u0648\u0646\u067e\u0646\u0627 \u06c1\u06d2\u06d4<br \/>\n\u0627\u0646\u06c1\u0648\u06ba\u0646\u06d2 \u067e\u06c1\u0644\u06af\u0627\u0645 \u0648\u0627\u0642\u0639\u06d2 \u06a9\u06d2 \u0628\u0639\u062f \u0646\u06c1\u062a\u06d2 \u06a9\u0634\u0645\u06cc\u0631\u06cc\u0648\u06ba \u067e\u0631 \u0628\u0691\u06be\u062a\u06cc \u06c1\u0648\u0626\u06cc \u0628\u06be\u0627\u0631\u062a\u06cc \u0631\u06cc\u0627\u0633\u062a\u06cc \u062f\u06c1\u0634\u062a \u06af\u0631\u062f\u06cc \u06a9\u06cc \u0634\u062f\u06cc\u062f \u0645\u0630\u0645\u062a \u06a9\u0631\u062a\u06d2 \u06c1\u0648\u0626\u06d2 \u06a9\u06c1\u0627 \u06a9\u06c1 \u0628\u06d2 \u0644\u06af\u0627\u0645 \u0628\u06be\u0627\u0631\u062a\u06cc \u0641\u0648\u0631\u0633\u0632 \u0646\u06d2 \u06a9\u0634\u0645\u06cc\u0631\u06cc\u0648\u06ba\u06a9\u06cc \u0632\u0646\u062f\u06af\u06cc \u0627\u062c\u06cc\u0631\u0646 \u0628\u0646\u0627 \u0631\u06a9\u06be\u06cc \u06c1\u06d2 \u06d4 \u0627\u0646\u06c1\u0648\u06ba\u0646\u06d2 \u06a9\u06c1\u0627 \u06a9\u06c1 \u0642\u0627\u0628\u0636 \u0641\u0648\u0631\u0633\u0632 \u0646\u06d2 \u06af\u0632\u0634\u062a\u06c1 \u0688\u06cc\u0691\u06be \u06c1\u0641\u062a\u06d2 \u06a9\u06d2 \u062f\u0648\u0631\u0627\u0646 25\u0633\u0648 \u0632\u0627\u0626\u062f \u06a9\u0634\u0645\u06cc\u0631\u06cc\u0648\u06ba\u06a9\u0648 \u06af\u0631\u0641\u062a\u0627\u0631 \u06a9\u06cc\u0627 \u062c\u0646 \u0645\u06cc\u06ba \u0633\u06d2 \u0633\u0648 \u06a9\u06d2 \u0644\u06af \u0628\u06be\u06af \u067e\u0631 \u06a9\u0627\u0644\u0627 \u0642\u0627\u0646\u0648\u0646\u201d\u067e\u0628\u0644\u06a9 \u0633\u06cc\u0641\u0679\u06cc \u0627\u06cc\u06a9\u0679\u201c\u0644\u0627\u06af\u0648 \u06a9\u06cc\u0627 \u06af\u06cc\u0627 \u06c1\u06d2\u06d4<br \/>\n\u062a\u0631\u062c\u0645\u0627\u0646 \u0646\u06d2 \u06a9\u06c1\u0627 \u06a9\u06c1 \u067e\u0627\u06a9\u0633\u062a\u0627\u0646 \u06a9\u06d2 \u062e\u0644\u0627\u0641 \u062f\u06c1\u0634\u062a \u06af\u0631\u062f\u06cc \u06a9\u0627 \u0631\u0627\u06af \u0627\u0644\u0627\u067e\u0646\u06d2 \u0648\u0627\u0644\u06d2 \u0628\u06be\u0627\u0631\u062a \u06a9\u06cc \u062f\u06c1\u0634\u062a \u06af\u0631\u062f\u0627\u0646\u06c1 \u06a9\u0627\u0631\u0648\u0627\u0626\u06cc\u0648\u06ba \u0646\u06d2 \u0646\u06c1 \u0635\u0631\u0641 \u06a9\u0634\u0645\u06cc\u0631\u06cc\u0648\u06ba \u06a9\u06cc \u0632\u0646\u062f\u06af\u06cc \u0627\u062c\u06cc\u0631\u0646 \u0628\u0646\u0627 \u0631\u06a9\u06be\u06cc \u06c1\u06d2 \u0628\u0644\u06a9\u06c1 \u0639\u0627\u0644\u0645\u06cc \u0627\u0645\u0646 \u0628\u06be\u06cc \u062f\u0627\ufe85 \u067e\u0631 \u0644\u06af\u0627 \u0631\u06a9\u06be\u0627 \u06c1\u06d2\u06d4<br \/>\n\u06a9\u0644 \u062c\u0645\u0627\u0639\u062a\u06cc \u062d\u0631\u06cc\u062a \u06a9\u0627\u0646\u0641\u0631\u0646\u0633 \u06a9\u06d2 \u062a\u0631\u062c\u0645\u0627\u0646 \u0646\u06d2 \u06a9\u06c1\u0627 \u06a9\u06c1 \u0628\u06be\u0627\u0631\u062a \u06a9\u0648 \u0686\u0627\u06c1\u06cc\u06d2 \u06a9\u06c1 \u0648\u06c1 \u062a\u0646\u0627\u0632\u0639\u06c1 \u06a9\u0634\u0645\u06cc\u0631\u06a9\u0648 \u0641\u0648\u062c\u06cc \u0637\u0627\u0642\u062a \u06a9\u06d2 \u0630\u0631\u06cc\u0639\u06d2 \u062d\u0644 \u06a9\u0631\u0646\u06d2 \u06a9\u06cc \u0627\u067e\u0646\u06cc \u0645\u0630\u0645\u0648\u0645 \u0633\u0648\u0686 \u062a\u0631\u06a9 \u0627\u0648\u0631\u06a9\u0634\u0645\u06cc\u0631\u06cc\u0648\u06ba \u0633\u06d2 \u06a9\u06cc\u06d2 \u06af\u0626\u06d2 \u0648\u0639\u062f\u06d2 \u067e\u0648\u0631\u06d2 \u06a9\u0631\u06d2 \u060c \u0627\u0633\u06cc \u0645\u06cc\u06ba \u0646\u06c1 \u0635\u0631\u0641 \u0627\u0633\u06a9\u06cc \u0628\u0644\u06a9\u06c1 \u0627\u0633 \u067e\u0648\u0631\u06d2 \u062e\u0637\u06d2 \u06a9\u06cc \u0628\u06be\u0644\u0627\u0626\u06cc \u06c1\u06d2\u06d4KMS-10\/M<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0633\u0631\u06cc\u0646\u06af\u0631: \u0628\u06be\u0627\u0631\u062a \u06a9\u06d2 \u063a\u06cc\u0631 \u0642\u0627\u0646\u0648\u0646\u06cc \u0632\u06cc\u0631 \u0642\u0628\u0636\u06c1 \u062c\u0645\u0648\u06ba \u0648\u06a9\u0634\u0645\u06cc\u0631 \u0645\u06cc\u06ba \u06a9\u0644 \u062c\u0645\u0627\u0639\u062a\u06cc \u062d\u0631\u06cc\u062a \u06a9\u0627\u0646\u0641\u0631\u0646\u0633 \u0646\u06d2 \u06a9\u06c1\u0627 \u06c1\u06d2 \u06a9\u06c1 \u0628\u06be\u0627\u0631\u062a \u062f\u06be\u0648\u06a9\u06c1 \u062f\u06c1\u06cc \u0627\u0648\u0631 \u0648\u0639\u062f\u06c1 \u062e\u0644\u0627\u0641\u06cc \u06a9\u06cc \u0627\u06cc\u06a9 \u06af\u06be\u0646\u0627\ufe85\u0646\u06cc \u062a\u0627\u0631\u06cc\u062e \u0631\u06a9\u06be\u062a\u0627 \u06c1\u06d2 \u060c \u062c\u0645\u0648\u06ba \u0648\u06a9\u0634\u0645\u06cc\u0631 \u067e\u0631 \u0646\u0627\u062c\u0627\u0626\u0632 \u0628\u06be\u0627\u0631\u062a\u06cc \u062a\u0633\u0644\u0637 \u06a9\u06cc \u0648\u062c\u06c1 \u0633\u06d2 \u06cc\u06c1 \u067e\u0648\u0631\u0627 \u062e\u0637\u06c1 \u0645\u0633\u0644\u0633\u0644 \u0627\u06cc\u06a9 \u063a\u06cc\u0631 \u06cc\u0642\u06cc\u0646\u06cc \u0635\u0648\u0631\u062a\u062d\u0627\u0644 \u0633\u06d2 \u062f\u0648\u0686\u0627\u0631 \u06c1\u06d2\u06d4 \u06a9\u0634\u0645\u06cc\u0631 \u0645\u06cc\u0688\u06cc\u0627\u0633\u0631\u0648\u0633 \u06a9\u06d2 \u0645\u0637\u0627\u0628\u0642 &hellip;<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[12],"tags":[],"class_list":["post-71955","post","type-post","status-publish","format-standard","hentry","category-aphc"],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/kmsnews.org\/urdu\/wp-json\/wp\/v2\/posts\/71955","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kmsnews.org\/urdu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kmsnews.org\/urdu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kmsnews.org\/urdu\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/kmsnews.org\/urdu\/wp-json\/wp\/v2\/comments?post=71955"}],"version-history":[{"count":0,"href":"https:\/\/kmsnews.org\/urdu\/wp-json\/wp\/v2\/posts\/71955\/revisions"}],"wp:attachment":[{"href":"https:\/\/kmsnews.org\/urdu\/wp-json\/wp\/v2\/media?parent=71955"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kmsnews.org\/urdu\/wp-json\/wp\/v2\/categories?post=71955"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kmsnews.org\/urdu\/wp-json\/wp\/v2\/tags?post=71955"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}