{"id":79785,"date":"2025-09-26T18:10:18","date_gmt":"2025-09-26T13:10:18","guid":{"rendered":"https:\/\/kmsnews.org\/urdu\/?p=79785"},"modified":"2025-09-26T18:10:18","modified_gmt":"2025-09-26T13:10:18","slug":"%d8%a8%da%be%d8%a7%d8%b1%d8%aa%db%8c-%d9%88%d8%b2%d8%a7%d8%b1%d8%aa-%d8%af%d8%a7%d8%ae%d9%84%db%81-%d9%86%db%92-%d8%b3%d9%88%d9%86%d9%85-%d9%88%d8%a7%d9%86%da%af%da%86%da%a9-%da%a9%db%8c","status":"publish","type":"post","link":"https:\/\/kmsnews.org\/urdu\/79785","title":{"rendered":"\u0628\u06be\u0627\u0631\u062a\u06cc \u0648\u0632\u0627\u0631\u062a \u062f\u0627\u062e\u0644\u06c1 \u0646\u06d2 \u0633\u0648\u0646\u0645 \u0648\u0627\u0646\u06af\u0686\u06a9 \u06a9\u06cc\u201d \u0627\u06cc\u0646 \u062c\u06cc \u0627\u0648\u201c \u067e\u0631 \u067e\u0627\u0628\u0646\u062f\u06cc \u0639\u0627\u0626\u062f \u06a9\u0631 \u062f\u06cc"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-79787\" src=\"https:\/\/kmsnews.org\/urdu\/assets\/2025\/09\/wanguch-1.jpg\" alt=\"\" width=\"240\" height=\"180\" \/><\/p>\n<p>\u0644\u06c1\u06c1 :\u0628\u06be\u0627\u0631\u062a\u06cc \u0648\u0632\u0627\u0631\u062a \u062f\u0627\u062e\u0644\u06c1 \u0646\u06d2 \u0645\u0642\u0628\u0648\u0636\u06c1 \u062c\u0645\u0648\u06ba \u0648 \u06a9\u0634\u0645\u06cc\u0631 \u06a9\u06d2 \u062e\u0637\u06d2 \u0644\u062f\u0627\u062e \u06a9\u06d2 \u0639\u0648\u0627\u0645 \u06a9\u06d2 \u0631\u06cc\u0627\u0633\u062a\u06cc \u062d\u0642\u0648\u0642 \u06a9\u06cc\u0644\u0626\u06d2 \u062c\u062f\u0648\u062c\u06c1\u062f \u067e\u0631 \u0645\u0627\u062d\u0648\u0644\u06cc\u0627\u062a\u06cc \u06a9\u0627\u0631\u06a9\u0646 \u0633\u0648\u0646\u0645 \u0648\u0627\u0646\u06af\u0686\u06a9 \u06a9\u06cc \u063a\u06cc\u0631 \u0633\u0631\u06a9\u0627\u0631\u06cc \u062a\u0646\u0638\u06cc\u0645\u060c \u0627\u0633\u0679\u0648\u0688\u0646\u0679\u0633 \u0627\u06cc\u062c\u0648\u06a9\u06cc\u0634\u0646\u0644 \u0627\u06cc\u0646\u0688 \u06a9\u0644\u0686\u0631\u0644 \u0645\u0648\u0648\u0645\u0646\u0679 \u0622\u0641 \u0644\u062f\u0627\u062e \u067e\u0631 \u067e\u0627\u0628\u0646\u062f\u06cc \u0639\u0627\u0626\u062f \u06a9\u0631 \u062f\u06cc \u06c1\u06d2\u06d4<br \/>\n\u06a9\u0634\u0645\u06cc\u0631 \u0645\u06cc\u0688\u06cc\u0627 \u0633\u0631\u0648\u0633 \u06a9\u06d2 \u0645\u0637\u0627\u0628\u0642 \u0628\u062f\u06be \u06a9\u0648 \u0644\u062f\u0627\u062e \u06a9\u06d2 \u0634\u06c1\u0631\u0644\u06c1\u06c1 \u0645\u06cc\u06ba \u0627\u067e\u0646\u06d2 \u0633\u06cc\u0627\u0633\u06cc \u062d\u0642\u0648\u0642 \u06a9\u06d2 \u0644\u06cc\u06d2 \u0627\u062d\u062a\u062c\u0627\u062c \u06a9\u0631\u0646\u06d2 \u0648\u0627\u0644\u06d2 \u0644\u0648\u06af\u0648\u06ba \u067e\u0631 \u0628\u06be\u0627\u0631\u062a\u06cc \u0641\u0648\u0631\u0633\u0632 \u06a9\u06cc \u0641\u0627\u0626\u0631\u0646\u06af \u0633\u06d2 \u0686\u0627\u0631 \u0627\u0641\u0631\u0627\u062f \u0642\u062a\u0644 \u0627\u0648\u0631 \u0633\u062a\u0631 \u0633\u06d2 \u0632\u0627\u0626\u062f \u0632\u062e\u0645\u06cc \u06c1\u0648 \u06af\u0626\u06d2 \u062a\u06be\u06d2 \u06d4\u0628\u06be\u0627\u0631\u062a\u06cc \u0648\u0632\u0627\u0631\u062a \u062f\u0627\u062e\u0644\u06c1 \u0646\u06d2 \u0645\u0627\u062d\u0648\u0644\u06cc\u0627\u062a\u06cc \u06a9\u0627\u0631\u06a9\u0646 \u0633\u0648\u0646\u0645 \u0648\u0627\u0646\u06af\u0686\u06a9 \u06a9\u06cc \u0627\u06cc\u0646 \u062c\u06cc \u0627\u0648 \u06a9\u0627 \u0644\u0627\u0626\u0633\u0646\u0633 \u0645\u0646\u0633\u0648\u062e \u06a9\u0631 \u062f\u06cc\u0627\u06d4\u0648\u0627\u0646\u06af\u0686\u06a9 \u0646\u06d2 \u062f\u0633 \u0633\u062a\u0645\u0628\u0631 \u06a9\u0648 \u0644\u062f\u0627\u062e \u06a9\u06cc \u0631\u06cc\u0627\u0633\u062a\u06cc \u062d\u06cc\u062b\u06cc\u062a \u0627\u0648\u0631 \u0686\u06be\u0679\u06d2 \u0634\u06cc\u0688\u0648\u0644 \u0645\u06cc\u06ba \u0634\u0645\u0648\u0644\u06cc\u062a \u06a9\u06d2 \u0645\u0637\u0627\u0644\u0628\u06d2 \u06a9\u06d2 \u062d\u0642 \u0645\u06cc\u06ba \u0628\u06be\u0648\u06a9 \u06c1\u0691\u062a\u0627\u0644 \u0634\u0631\u0648\u0639 \u06a9\u06cc \u062a\u06be\u06cc \u06d4\u0628\u06be\u0627\u0631\u062a\u06cc \u0648\u0632\u0627\u0631\u062a \u062f\u0627\u062e\u0644\u06c1 \u0646\u06d2 \u0627\u06cc\u06a9 \u0628\u06cc\u0627\u0646 \u0645\u06cc\u06ba\u0633\u0648\u0646\u0645 \u0648\u0627\u0646\u06af\u0686\u06a9 \u06a9\u0648 \u0644\u062f\u0627\u062e \u06a9\u06cc \u06a9\u0634\u06cc\u062f\u06c1 \u0635\u0648\u0631\u062a\u062d\u0627\u0644 \u06a9\u0627\u0630\u0645\u06c1 \u062f\u0627\u0631 \u0642\u0631\u0627\u0631\u062f\u06cc\u0627\u06c1\u06d2<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0644\u06c1\u06c1 :\u0628\u06be\u0627\u0631\u062a\u06cc \u0648\u0632\u0627\u0631\u062a \u062f\u0627\u062e\u0644\u06c1 \u0646\u06d2 \u0645\u0642\u0628\u0648\u0636\u06c1 \u062c\u0645\u0648\u06ba \u0648 \u06a9\u0634\u0645\u06cc\u0631 \u06a9\u06d2 \u062e\u0637\u06d2 \u0644\u062f\u0627\u062e \u06a9\u06d2 \u0639\u0648\u0627\u0645 \u06a9\u06d2 \u0631\u06cc\u0627\u0633\u062a\u06cc \u062d\u0642\u0648\u0642 \u06a9\u06cc\u0644\u0626\u06d2 \u062c\u062f\u0648\u062c\u06c1\u062f \u067e\u0631 \u0645\u0627\u062d\u0648\u0644\u06cc\u0627\u062a\u06cc \u06a9\u0627\u0631\u06a9\u0646 \u0633\u0648\u0646\u0645 \u0648\u0627\u0646\u06af\u0686\u06a9 \u06a9\u06cc \u063a\u06cc\u0631 \u0633\u0631\u06a9\u0627\u0631\u06cc \u062a\u0646\u0638\u06cc\u0645\u060c \u0627\u0633\u0679\u0648\u0688\u0646\u0679\u0633 \u0627\u06cc\u062c\u0648\u06a9\u06cc\u0634\u0646\u0644 \u0627\u06cc\u0646\u0688 \u06a9\u0644\u0686\u0631\u0644 \u0645\u0648\u0648\u0645\u0646\u0679 \u0622\u0641 \u0644\u062f\u0627\u062e \u067e\u0631 \u067e\u0627\u0628\u0646\u062f\u06cc \u0639\u0627\u0626\u062f \u06a9\u0631 \u062f\u06cc \u06c1\u06d2\u06d4 \u06a9\u0634\u0645\u06cc\u0631 \u0645\u06cc\u0688\u06cc\u0627 \u0633\u0631\u0648\u0633 \u06a9\u06d2 \u0645\u0637\u0627\u0628\u0642 \u0628\u062f\u06be \u06a9\u0648 \u0644\u062f\u0627\u062e \u06a9\u06d2 \u0634\u06c1\u0631\u0644\u06c1\u06c1 \u0645\u06cc\u06ba \u0627\u067e\u0646\u06d2 \u0633\u06cc\u0627\u0633\u06cc \u062d\u0642\u0648\u0642 &hellip;<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[26],"tags":[],"class_list":["post-79785","post","type-post","status-publish","format-standard","hentry","category-26"],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/kmsnews.org\/urdu\/wp-json\/wp\/v2\/posts\/79785","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kmsnews.org\/urdu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kmsnews.org\/urdu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kmsnews.org\/urdu\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/kmsnews.org\/urdu\/wp-json\/wp\/v2\/comments?post=79785"}],"version-history":[{"count":1,"href":"https:\/\/kmsnews.org\/urdu\/wp-json\/wp\/v2\/posts\/79785\/revisions"}],"predecessor-version":[{"id":79788,"href":"https:\/\/kmsnews.org\/urdu\/wp-json\/wp\/v2\/posts\/79785\/revisions\/79788"}],"wp:attachment":[{"href":"https:\/\/kmsnews.org\/urdu\/wp-json\/wp\/v2\/media?parent=79785"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kmsnews.org\/urdu\/wp-json\/wp\/v2\/categories?post=79785"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kmsnews.org\/urdu\/wp-json\/wp\/v2\/tags?post=79785"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}