{"id":91744,"date":"2026-05-13T19:16:03","date_gmt":"2026-05-13T14:16:03","guid":{"rendered":"https:\/\/kmsnews.org\/urdu\/?p=91744"},"modified":"2026-05-13T19:16:03","modified_gmt":"2026-05-13T14:16:03","slug":"%d8%a2%d8%ba%d8%a7-%d8%b3%db%8c%d8%af-%d8%ad%d8%b3%d9%86-%da%a9%d8%a7%d8%b4%d8%a7%d9%84%db%8c%d9%85%d8%a7%d8%b1-%d8%b3%d8%b1%db%8c%d9%86%da%af%d8%b1-%d9%85%db%8c%da%ba-%d9%86%d9%88%d8%ac%d9%88%d8%a7","status":"publish","type":"post","link":"https:\/\/kmsnews.org\/urdu\/91744","title":{"rendered":"\u0622\u063a\u0627 \u0633\u06cc\u062f \u062d\u0633\u0646 \u06a9\u0627\u0634\u0627\u0644\u06cc\u0645\u0627\u0631 \u0633\u0631\u06cc\u0646\u06af\u0631 \u0645\u06cc\u06ba \u0646\u0648\u062c\u0648\u0627\u0646 \u06a9\u06cc \u06af\u0631\u0641\u062a\u0627\u0631\u06cc \u067e\u0631\u0627\u0638\u06c1\u0627\u0631\u062a\u0634\u0648\u06cc\u0634"},"content":{"rendered":"<p>\u0633\u0631\u06cc\u0646\u06af\u0631: \u063a\u06cc\u0631\u0642\u0627\u0646\u0648\u0646\u06cc \u0637\u0648\u0631\u067e\u0631 \u0628\u06be\u0627\u0631\u062a \u06a9\u06d2 \u0632\u06cc\u0631 \u0642\u0628\u0636\u06c1 \u062c\u0645\u0648\u06ba \u0648\u06a9\u0634\u0645\u06cc\u0631 \u0645\u06cc\u06ba \u0627\u0646\u062c\u0645\u0646 \u0634\u0631\u0639\u06cc \u0634\u06cc\u0639\u06cc\u0627\u0646 \u06a9\u06d2 \u0635\u062f\u0631 \u0622\u063a\u0627 \u0633\u06cc\u062f \u062d\u0633\u0646 \u0627\u0644\u0645\u0648\u0633\u0648\u06cc \u0627\u0644\u0635\u0641\u0648\u06cc \u0646\u06d2 \u0634\u0627\u0644\u06cc\u0645\u0627\u0631 \u0633\u0631\u06cc\u0646\u06af\u0631 \u06a9\u06d2 \u0646\u0648\u062c\u0648\u0627\u0646 \u0627\u0631\u0628\u0627\u0632 \u0639\u0644\u06cc \u0628\u0679 \u06a9\u06cc \u06af\u0631\u0641\u062a\u0627\u0631\u06cc \u067e\u0631 \u0634\u062f\u06cc\u062f \u062a\u0634\u0648\u06cc\u0634 \u06a9\u0627 \u0627\u0638\u06c1\u0627\u0631 \u06a9\u0631\u062a\u06d2 \u06c1\u0648\u0626\u06d2 \u06a9\u06c1\u0627 \u06c1\u06d2 \u06a9\u06c1 \u0639\u0648\u0627\u0645\u06cc \u062c\u0630\u0628\u0627\u062a \u0627\u0648\u0631 \u0645\u0630\u06c1\u0628\u06cc \u0648\u0627\u0628\u0633\u062a\u06af\u06cc \u06a9\u06d2 \u0627\u0638\u06c1\u0627\u0631 \u06a9\u0648 \u062c\u0631\u0645 \u0642\u0631\u0627\u0631 \u062f\u06cc\u0646\u0627 \u0646\u06c1 \u0635\u0631\u0641 \u0627\u0641\u0633\u0648\u0633\u0646\u0627\u06a9 \u0628\u0644\u06a9\u06c1 \u0628\u0646\u06cc\u0627\u062f\u06cc \u0627\u0646\u0633\u0627\u0646\u06cc \u062d\u0642\u0648\u0642 \u06a9\u06cc \u062e\u0644\u0627\u0641 \u0648\u0631\u0632\u06cc \u06c1\u06d2\u06d4<br \/>\n\u06a9\u0634\u0645\u06cc\u0631\u0645\u06cc\u0688\u06cc\u0627\u0633\u0631\u0648\u0633 \u06a9\u06d2 \u0645\u0637\u0627\u0628\u0642 \u0622\u063a\u0627 \u0633\u06cc\u062f \u062d\u0633\u0646 \u0646\u06d2 \u0633\u0631\u06cc\u0646\u06af\u0631 \u0645\u06cc\u06ba \u062c\u0627\u0631\u06cc \u0627\u06cc\u06a9 \u0628\u06cc\u0627\u0646 \u0645\u06cc\u06ba \u06a9\u06c1\u0627 \u06a9\u06c1 \u0627\u0631\u0628\u0627\u0632 \u0639\u0644\u06cc \u0628\u0679 \u06a9\u0648 \u06af\u0632\u0634\u062a\u06c1 \u0631\u0648\u0632 \u0627\u0004\u00b1\u0646 \u06a9\u06d2 \u06af\u06be\u0631 \u0633\u06d2 \u0627\u0633 \u0628\u0646\u06cc\u0627\u062f \u067e\u0631 \u06af\u0631\u0641\u062a\u0627\u0631 \u06a9\u06cc\u0627 \u06af\u06cc\u0627 \u06a9\u06c1 \u0627\u0646\u06c1\u0648\u06ba \u0646\u06d2 28 \u0641\u0631\u0648\u0631\u06cc \u06a9\u0648 \u0627\u06cc\u0631\u0627\u0646 \u06a9\u06d2 \u0633\u067e\u0631\u06cc\u0645 \u0644\u06cc\u0688\u0631\u0622\u06cc\u062a \u0627\u0644\u0644\u06c1 \u0639\u0644\u06cc \u062e\u0627\u0645\u0646\u06c1 \u0627\u06cc \u06a9\u06cc \u0634\u06c1\u0627\u062f\u062a \u067e\u0631 \u0627\u0638\u06c1\u0627\u0631 \u063a\u0645 \u06a9\u06cc\u0627 \u062a\u06be\u0627\u06d4 \u0627\u0646\u06c1\u0648\u06ba \u0646\u06d2 \u06a9\u06c1\u0627 \u06a9\u06c1 \u06a9\u0633\u06cc \u0628\u06be\u06cc \u0641\u0631\u062f \u06a9\u0627 \u0627\u067e\u0646\u06d2 \u0645\u0630\u06c1\u0628\u06cc \u0648 \u0631\u0648\u062d\u0627\u0646\u06cc \u0631\u06c1\u0646\u0645\u0627 \u0633\u06d2 \u0639\u0642\u06cc\u062f\u062a \u0627\u0648\u0631 \u0645\u062d\u0628\u062a \u06a9\u0627 \u0627\u0638\u06c1\u0627\u0631 \u06a9\u0631\u0646\u0627 \u0627\u06cc\u06a9 \u0641\u0637\u0631\u06cc \u0627\u0648\u0631 \u062c\u0645\u06c1\u0648\u0631\u06cc \u062d\u0642 \u06c1\u06d2 \u062c\u0633\u06d2 \u0627\u0633 \u0637\u0631\u062d \u06a9\u06cc \u06a9\u0627\u0631\u0631\u0648\u0627\u0626\u06cc\u0648\u06ba \u06a9\u06d2 \u0630\u0631\u06cc\u0639\u06d2 \u062f\u0628\u0627\u06cc\u0627 \u0646\u06c1\u06cc\u06ba \u062c\u0627 \u0633\u06a9\u062a\u0627\u06d4\u0627\u0646\u06c1\u0648\u06ba \u0646\u06d2 \u0646\u0648\u062c\u0648\u0627\u0646 \u067e\u0631\u06a9\u0627\u0644\u0627 \u0642\u0627\u0646\u0648\u0646 \u067e\u0628\u0644\u06a9 \u0633\u06cc\u0641\u0679\u06cc \u0627\u06cc\u06a9\u0679 \u0639\u0627\u0626\u062f \u06a9\u0626\u06d2 \u062c\u0627\u0646\u06d2 \u06a9\u0648\u062a\u0634\u0648\u06cc\u0634\u0646\u0627\u06a9 \u0642\u0631\u0627\u0631 \u062f\u06cc\u062a\u06d2 \u06c1\u0648\u0626\u06d2 \u06a9\u06c1\u0627 \u06a9\u06c1 \u0627\u0633 \u0642\u0633\u0645 \u06a9\u06d2 \u0627\u0642\u062f\u0627\u0645\u0627\u062a \u0646\u0648\u062c\u0648\u0627\u0646 \u0646\u0633\u0644 \u0645\u06cc\u06ba \u0628\u06d2 \u0686\u06cc\u0646\u06cc \u0627\u0648\u0631 \u0627\u0636\u0637\u0631\u0627\u0628 \u067e\u06cc\u062f\u0627 \u06a9\u0631\u062a\u06d2 \u06c1\u06cc\u06ba\u06d4 \u0622\u063a\u0627 \u062d\u0633\u0646 \u0646\u06d2 \u0642\u0627\u0628\u0636 \u062d\u06a9\u0627\u0645 \u0633\u06d2 \u0645\u0637\u0627\u0644\u0628\u06c1 \u06a9\u06cc\u0627\u06a9\u06c1 \u0627\u0646\u0635\u0627\u0641 \u06a9\u06d2 \u062a\u0642\u0627\u0636\u0648\u06ba \u06a9\u0648 \u0645\u062f\u0646\u0638\u0631 \u0631\u06a9\u06be\u062a\u06d2 \u06c1\u0648\u0626\u06d2 \u0627\u0631\u0628\u0627\u0632 \u0639\u0644\u06cc \u0628\u0679 \u06a9\u0648 \u0641\u0648\u0631\u06cc \u0637\u0648\u0631\u067e\u0631 \u0631\u06c1\u0627 \u06a9\u06cc\u0627 \u062c\u0627\u0626\u06d2\u06d4<br \/>\n\u062f\u0631\u06cc\u06ba \u0627\u062b\u0646\u0627\u0621\u0634\u0627\u0644\u06cc\u0645\u0627\u0631 \u0645\u06cc\u06ba \u0646\u0648\u062c\u0648\u0627\u0646 \u06a9\u06cc \u06af\u0631\u0641\u062a\u0627\u0631\u06cc \u06a9\u06d2 \u062e\u0644\u0627\u0641 \u0645\u0642\u0627\u0645\u06cc \u0644\u0648\u06af\u0648\u06ba \u0646\u06d2 \u0627\u062d\u062a\u062c\u0627\u062c\u06cc \u0645\u0638\u0627\u06c1\u0631\u06c1 \u06a9\u0631\u062a\u06d2 \u06c1\u0648\u0626\u06d2 \u0627\u0633\u06d2 \u063a\u06cc\u0631 \u0645\u0646\u0635\u0641\u0627\u0646\u06c1 \u0642\u0631\u0627\u0631 \u062f\u06cc\u0627\u06d4 \u0645\u0638\u0627\u06c1\u0631\u06cc\u0646 \u0646\u06d2 \u062d\u06a9\u0627\u0645 \u0633\u06d2 \u0645\u0637\u0627\u0644\u0628\u06c1 \u06a9\u06cc\u0627 \u06a9\u06c1 \u0646\u0648\u062c\u0648\u0627\u0646 \u06a9\u0648 \u0641\u0648\u0631\u06cc \u0637\u0648\u0631 \u0631\u06c1\u0627 \u06a9\u06cc\u0627 \u062c\u0627\u0626\u06d2 \u0627\u0648\u0631 \u0639\u0648\u0627\u0645\u06cc \u062c\u0630\u0628\u0627\u062a \u06a9\u0627 \u0627\u062d\u062a\u0631\u0627\u0645 \u06a9\u06cc\u0627 \u062c\u0627\u0626\u06d2\u06d4<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0633\u0631\u06cc\u0646\u06af\u0631: \u063a\u06cc\u0631\u0642\u0627\u0646\u0648\u0646\u06cc \u0637\u0648\u0631\u067e\u0631 \u0628\u06be\u0627\u0631\u062a \u06a9\u06d2 \u0632\u06cc\u0631 \u0642\u0628\u0636\u06c1 \u062c\u0645\u0648\u06ba \u0648\u06a9\u0634\u0645\u06cc\u0631 \u0645\u06cc\u06ba \u0627\u0646\u062c\u0645\u0646 \u0634\u0631\u0639\u06cc \u0634\u06cc\u0639\u06cc\u0627\u0646 \u06a9\u06d2 \u0635\u062f\u0631 \u0622\u063a\u0627 \u0633\u06cc\u062f \u062d\u0633\u0646 \u0627\u0644\u0645\u0648\u0633\u0648\u06cc \u0627\u0644\u0635\u0641\u0648\u06cc \u0646\u06d2 \u0634\u0627\u0644\u06cc\u0645\u0627\u0631 \u0633\u0631\u06cc\u0646\u06af\u0631 \u06a9\u06d2 \u0646\u0648\u062c\u0648\u0627\u0646 \u0627\u0631\u0628\u0627\u0632 \u0639\u0644\u06cc \u0628\u0679 \u06a9\u06cc \u06af\u0631\u0641\u062a\u0627\u0631\u06cc \u067e\u0631 \u0634\u062f\u06cc\u062f \u062a\u0634\u0648\u06cc\u0634 \u06a9\u0627 \u0627\u0638\u06c1\u0627\u0631 \u06a9\u0631\u062a\u06d2 \u06c1\u0648\u0626\u06d2 \u06a9\u06c1\u0627 \u06c1\u06d2 \u06a9\u06c1 \u0639\u0648\u0627\u0645\u06cc \u062c\u0630\u0628\u0627\u062a \u0627\u0648\u0631 \u0645\u0630\u06c1\u0628\u06cc \u0648\u0627\u0628\u0633\u062a\u06af\u06cc \u06a9\u06d2 \u0627\u0638\u06c1\u0627\u0631 \u06a9\u0648 \u062c\u0631\u0645 \u0642\u0631\u0627\u0631 \u062f\u06cc\u0646\u0627 \u0646\u06c1 \u0635\u0631\u0641 \u0627\u0641\u0633\u0648\u0633\u0646\u0627\u06a9 \u0628\u0644\u06a9\u06c1 &hellip;<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[2],"tags":[],"class_list":["post-91744","post","type-post","status-publish","format-standard","hentry","category-breaking-and-latest-news-in-urdu-from-jammu-and-kashmir"],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/kmsnews.org\/urdu\/wp-json\/wp\/v2\/posts\/91744","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kmsnews.org\/urdu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kmsnews.org\/urdu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kmsnews.org\/urdu\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/kmsnews.org\/urdu\/wp-json\/wp\/v2\/comments?post=91744"}],"version-history":[{"count":1,"href":"https:\/\/kmsnews.org\/urdu\/wp-json\/wp\/v2\/posts\/91744\/revisions"}],"predecessor-version":[{"id":91745,"href":"https:\/\/kmsnews.org\/urdu\/wp-json\/wp\/v2\/posts\/91744\/revisions\/91745"}],"wp:attachment":[{"href":"https:\/\/kmsnews.org\/urdu\/wp-json\/wp\/v2\/media?parent=91744"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kmsnews.org\/urdu\/wp-json\/wp\/v2\/categories?post=91744"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kmsnews.org\/urdu\/wp-json\/wp\/v2\/tags?post=91744"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}